{"id":3203,"date":"2023-12-19T12:30:23","date_gmt":"2023-12-19T11:30:23","guid":{"rendered":"https:\/\/www.palermocityguides.com\/?p=3203"},"modified":"2023-12-19T14:42:52","modified_gmt":"2023-12-19T13:42:52","slug":"dicembre-a-palermo","status":"publish","type":"post","link":"https:\/\/www.palermocityguides.com\/it\/news\/dicembre-a-palermo\/","title":{"rendered":"Dicembre a Palermo"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Cari amici, ci ritroviamo insieme a dicembre a Palermo e vogliamo dire grazie ai tanti di voi che hanno mostrato interesse e apprezzamento per la nostra isola e il suo capoluogo. Il 2023 che ormai volge al termine \u00e8 stato davvero un anno ricco di incontri simpatici e di belle soddisfazioni!<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Insieme a noi anche il caldo sole che a dicembre a Palermo continua ad accompagnarci e che ci ha indotti a riunirci per pensare per voi nuovi percorsi di visita ed esperienze. Nasceranno nuovi itinerari per l&#8217;anno che verr\u00e0, programmi attraverso i quali farvi conoscere anche le eccellenze enogastronomiche siciliane. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Il centro storico intanto \u00e8 diventato m\u00e8ta di tanti palermitani che da tutti i quartieri della citt\u00e0 si spostano per scoprire un nuovo spazio. E&#8217; il <a href=\"https:\/\/ilgiornaledellarchitettura.com\/2023\/10\/25\/palermo-marina-yachting-una-ferita-sanata\/\">Marina Yachting Palermo<\/a>, che ha riportato Palermo in stretto contatto con il suo mare. In un tratto di costa per anni preda del degrado e inaccessibile, \u00e8 stata portata a termine una attenta riqualificazione.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Adesso si pu\u00f2 passeggiare sul lungomare tra le antiche mura, i bastioni cinquecenteschi e nuovi giochi d&#8217;acqua. In uno dei nuovi locali si possono degustare vini siciliani di qualit\u00e0, scegliere pietanze ricercate a base di prodotti locali o provare il tipico cibo da strada. Senza dover rinunciare allo shopping in eleganti negozi dove andare alla ricerca del vero Made in Italy.  Se e quando verrete o tornerete in vacanza a Palermo, sedetevi di fronte al mare per godervi la vista di un paesaggio mozzafiato. I vostri occhi potranno posarsi sulle barche ancorate al molo, sulle guglie e sulle cupole delle chiese del centro storico o sul nostro monte sacro, Monte Pellegrino. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Vi aspettiamo per raccontarvi ancora della nostra citt\u00e0, del suo passato, del suo presente e dei progetti per il futuro. Intanto vi auguriamo buon Natale e un sereno e prospero nuovo anno.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Silvia, Gino e Maril\u00fa<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cari amici, ci ritroviamo insieme a dicembre a Palermo e vogliamo dire grazie ai tanti di voi che hanno mostrato interesse e apprezzamento per la nostra isola e il suo capoluogo. Il 2023 che ormai volge al termine \u00e8 stato davvero un anno ricco di incontri simpatici e di belle soddisfazioni! Insieme a noi anche [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":3204,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-3203","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Dicembre a Palermo - Palermo City Guides<\/title>\n<meta name=\"description\" content=\"Amici, a Dicembre a Palermo ci riscalda il sole! In attesa del 2024 grazie per il meraviglioso 2023. Buone feste! Silvia, Gino e Maril\u00fa\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.palermocityguides.com\/it\/news\/dicembre-a-palermo\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Dicembre a Palermo - Palermo City Guides\" \/>\n<meta property=\"og:description\" content=\"Amici, a Dicembre a Palermo ci riscalda il sole! In attesa del 2024 grazie per il meraviglioso 2023. Buone feste! Silvia, Gino e Maril\u00fa\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.palermocityguides.com\/it\/news\/dicembre-a-palermo\/\" \/>\n<meta property=\"og:site_name\" content=\"Palermo City Guides\" \/>\n<meta property=\"article:published_time\" content=\"2023-12-19T11:30:23+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-12-19T13:42:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/storage1045.cdn-immedia.net\/wp-content\/uploads\/2023\/12\/Amici-al-lavoro.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2448\" \/>\n\t<meta property=\"og:image:height\" content=\"1836\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Silvia Lombardo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Silvia Lombardo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.palermocityguides.com\\\/it\\\/news\\\/dicembre-a-palermo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.palermocityguides.com\\\/it\\\/news\\\/dicembre-a-palermo\\\/\"},\"author\":{\"name\":\"Silvia Lombardo\",\"@id\":\"https:\\\/\\\/www.palermocityguides.com\\\/it\\\/#\\\/schema\\\/person\\\/7a8817f2a33f343f4bd209b6727fe6b5\"},\"headline\":\"Dicembre a Palermo\",\"datePublished\":\"2023-12-19T11:30:23+00:00\",\"dateModified\":\"2023-12-19T13:42:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.palermocityguides.com\\\/it\\\/news\\\/dicembre-a-palermo\\\/\"},\"wordCount\":310,\"publisher\":{\"@id\":\"https:\\\/\\\/www.palermocityguides.com\\\/it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.palermocityguides.com\\\/it\\\/news\\\/dicembre-a-palermo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.palermocityguides.com\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/Amici-al-lavoro.jpg\",\"articleSection\":[\"News\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.palermocityguides.com\\\/it\\\/news\\\/dicembre-a-palermo\\\/\",\"url\":\"https:\\\/\\\/www.palermocityguides.com\\\/it\\\/news\\\/dicembre-a-palermo\\\/\",\"name\":\"Dicembre a Palermo - Palermo City Guides\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.palermocityguides.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.palermocityguides.com\\\/it\\\/news\\\/dicembre-a-palermo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.palermocityguides.com\\\/it\\\/news\\\/dicembre-a-palermo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.palermocityguides.com\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/Amici-al-lavoro.jpg\",\"datePublished\":\"2023-12-19T11:30:23+00:00\",\"dateModified\":\"2023-12-19T13:42:52+00:00\",\"description\":\"Amici, a Dicembre a Palermo ci riscalda il sole! In attesa del 2024 grazie per il meraviglioso 2023. Buone feste! Silvia, Gino e Maril\u00fa\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.palermocityguides.com\\\/it\\\/news\\\/dicembre-a-palermo\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.palermocityguides.com\\\/it\\\/news\\\/dicembre-a-palermo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.palermocityguides.com\\\/it\\\/news\\\/dicembre-a-palermo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.palermocityguides.com\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/Amici-al-lavoro.jpg\",\"contentUrl\":\"https:\\\/\\\/www.palermocityguides.com\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/Amici-al-lavoro.jpg\",\"width\":2448,\"height\":1836,\"caption\":\"Dicembre, amici al lavoro a Palermo\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.palermocityguides.com\\\/it\\\/news\\\/dicembre-a-palermo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.palermocityguides.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Dicembre a Palermo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.palermocityguides.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/www.palermocityguides.com\\\/it\\\/\",\"name\":\"Palermo City Guides\",\"description\":\"Palermo City Guides\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.palermocityguides.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.palermocityguides.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.palermocityguides.com\\\/it\\\/#organization\",\"name\":\"Palermo City Guides\",\"url\":\"https:\\\/\\\/www.palermocityguides.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.palermocityguides.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.palermocityguides.com\\\/wp-content\\\/uploads\\\/2018\\\/01\\\/logo-palermo-city-guides.png\",\"contentUrl\":\"https:\\\/\\\/www.palermocityguides.com\\\/wp-content\\\/uploads\\\/2018\\\/01\\\/logo-palermo-city-guides.png\",\"width\":562,\"height\":213,\"caption\":\"Palermo City Guides\"},\"image\":{\"@id\":\"https:\\\/\\\/www.palermocityguides.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.palermocityguides.com\\\/it\\\/#\\\/schema\\\/person\\\/7a8817f2a33f343f4bd209b6727fe6b5\",\"name\":\"Silvia Lombardo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/43fe003c277ddf3a0f7a01b0d7c2a508566dbaa482af6edf8eb6ffb8c852d1b0?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/43fe003c277ddf3a0f7a01b0d7c2a508566dbaa482af6edf8eb6ffb8c852d1b0?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/43fe003c277ddf3a0f7a01b0d7c2a508566dbaa482af6edf8eb6ffb8c852d1b0?s=96&d=mm&r=g\",\"caption\":\"Silvia Lombardo\"},\"sameAs\":[\"http:\\\/\\\/www.palermocityguides.com\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Dicembre a Palermo - Palermo City Guides","description":"Amici, a Dicembre a Palermo ci riscalda il sole! In attesa del 2024 grazie per il meraviglioso 2023. Buone feste! Silvia, Gino e Maril\u00fa","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.palermocityguides.com\/it\/news\/dicembre-a-palermo\/","og_locale":"it_IT","og_type":"article","og_title":"Dicembre a Palermo - Palermo City Guides","og_description":"Amici, a Dicembre a Palermo ci riscalda il sole! In attesa del 2024 grazie per il meraviglioso 2023. Buone feste! Silvia, Gino e Maril\u00fa","og_url":"https:\/\/www.palermocityguides.com\/it\/news\/dicembre-a-palermo\/","og_site_name":"Palermo City Guides","article_published_time":"2023-12-19T11:30:23+00:00","article_modified_time":"2023-12-19T13:42:52+00:00","og_image":[{"width":2448,"height":1836,"url":"https:\/\/storage1045.cdn-immedia.net\/wp-content\/uploads\/2023\/12\/Amici-al-lavoro.jpg","type":"image\/jpeg"}],"author":"Silvia Lombardo","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Silvia Lombardo","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.palermocityguides.com\/it\/news\/dicembre-a-palermo\/#article","isPartOf":{"@id":"https:\/\/www.palermocityguides.com\/it\/news\/dicembre-a-palermo\/"},"author":{"name":"Silvia Lombardo","@id":"https:\/\/www.palermocityguides.com\/it\/#\/schema\/person\/7a8817f2a33f343f4bd209b6727fe6b5"},"headline":"Dicembre a Palermo","datePublished":"2023-12-19T11:30:23+00:00","dateModified":"2023-12-19T13:42:52+00:00","mainEntityOfPage":{"@id":"https:\/\/www.palermocityguides.com\/it\/news\/dicembre-a-palermo\/"},"wordCount":310,"publisher":{"@id":"https:\/\/www.palermocityguides.com\/it\/#organization"},"image":{"@id":"https:\/\/www.palermocityguides.com\/it\/news\/dicembre-a-palermo\/#primaryimage"},"thumbnailUrl":"https:\/\/storage1045.cdn-immedia.net\/wp-content\/uploads\/2023\/12\/Amici-al-lavoro.jpg","articleSection":["News"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.palermocityguides.com\/it\/news\/dicembre-a-palermo\/","url":"https:\/\/www.palermocityguides.com\/it\/news\/dicembre-a-palermo\/","name":"Dicembre a Palermo - Palermo City Guides","isPartOf":{"@id":"https:\/\/www.palermocityguides.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.palermocityguides.com\/it\/news\/dicembre-a-palermo\/#primaryimage"},"image":{"@id":"https:\/\/www.palermocityguides.com\/it\/news\/dicembre-a-palermo\/#primaryimage"},"thumbnailUrl":"https:\/\/storage1045.cdn-immedia.net\/wp-content\/uploads\/2023\/12\/Amici-al-lavoro.jpg","datePublished":"2023-12-19T11:30:23+00:00","dateModified":"2023-12-19T13:42:52+00:00","description":"Amici, a Dicembre a Palermo ci riscalda il sole! In attesa del 2024 grazie per il meraviglioso 2023. Buone feste! Silvia, Gino e Maril\u00fa","breadcrumb":{"@id":"https:\/\/www.palermocityguides.com\/it\/news\/dicembre-a-palermo\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.palermocityguides.com\/it\/news\/dicembre-a-palermo\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.palermocityguides.com\/it\/news\/dicembre-a-palermo\/#primaryimage","url":"https:\/\/storage1045.cdn-immedia.net\/wp-content\/uploads\/2023\/12\/Amici-al-lavoro.jpg","contentUrl":"https:\/\/storage1045.cdn-immedia.net\/wp-content\/uploads\/2023\/12\/Amici-al-lavoro.jpg","width":2448,"height":1836,"caption":"Dicembre, amici al lavoro a Palermo"},{"@type":"BreadcrumbList","@id":"https:\/\/www.palermocityguides.com\/it\/news\/dicembre-a-palermo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.palermocityguides.com\/it\/"},{"@type":"ListItem","position":2,"name":"Dicembre a Palermo"}]},{"@type":"WebSite","@id":"https:\/\/www.palermocityguides.com\/it\/#website","url":"https:\/\/www.palermocityguides.com\/it\/","name":"Palermo City Guides","description":"Palermo City Guides","publisher":{"@id":"https:\/\/www.palermocityguides.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.palermocityguides.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.palermocityguides.com\/it\/#organization","name":"Palermo City Guides","url":"https:\/\/www.palermocityguides.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.palermocityguides.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/storage1045.cdn-immedia.net\/wp-content\/uploads\/2018\/01\/logo-palermo-city-guides.png","contentUrl":"https:\/\/storage1045.cdn-immedia.net\/wp-content\/uploads\/2018\/01\/logo-palermo-city-guides.png","width":562,"height":213,"caption":"Palermo City Guides"},"image":{"@id":"https:\/\/www.palermocityguides.com\/it\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.palermocityguides.com\/it\/#\/schema\/person\/7a8817f2a33f343f4bd209b6727fe6b5","name":"Silvia Lombardo","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/43fe003c277ddf3a0f7a01b0d7c2a508566dbaa482af6edf8eb6ffb8c852d1b0?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/43fe003c277ddf3a0f7a01b0d7c2a508566dbaa482af6edf8eb6ffb8c852d1b0?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/43fe003c277ddf3a0f7a01b0d7c2a508566dbaa482af6edf8eb6ffb8c852d1b0?s=96&d=mm&r=g","caption":"Silvia Lombardo"},"sameAs":["http:\/\/www.palermocityguides.com"]}]}},"_links":{"self":[{"href":"https:\/\/www.palermocityguides.com\/it\/wp-json\/wp\/v2\/posts\/3203","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.palermocityguides.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.palermocityguides.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.palermocityguides.com\/it\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.palermocityguides.com\/it\/wp-json\/wp\/v2\/comments?post=3203"}],"version-history":[{"count":1,"href":"https:\/\/www.palermocityguides.com\/it\/wp-json\/wp\/v2\/posts\/3203\/revisions"}],"predecessor-version":[{"id":3216,"href":"https:\/\/www.palermocityguides.com\/it\/wp-json\/wp\/v2\/posts\/3203\/revisions\/3216"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.palermocityguides.com\/it\/wp-json\/wp\/v2\/media\/3204"}],"wp:attachment":[{"href":"https:\/\/www.palermocityguides.com\/it\/wp-json\/wp\/v2\/media?parent=3203"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.palermocityguides.com\/it\/wp-json\/wp\/v2\/categories?post=3203"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.palermocityguides.com\/it\/wp-json\/wp\/v2\/tags?post=3203"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}